{"id":9932,"date":"2019-07-12T15:57:16","date_gmt":"2019-07-12T13:57:16","guid":{"rendered":"https:\/\/blog.bandofboats.com\/?p=9932"},"modified":"2021-11-26T09:56:46","modified_gmt":"2021-11-26T08:56:46","slug":"quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera","status":"publish","type":"post","link":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/","title":{"rendered":"Quali sono i limiti della patente nautica per la navigazione costiera?"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.11.1&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sommaire&#8221; _builder_version=&#8221;4.11.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Source Sans Pro|600|||||||&#8221; text_line_height=&#8221;2em&#8221; link_text_color=&#8221;#3e6a91&#8243; background_color=&#8221;#fef9f5&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;50px||0px||false|false&#8221; custom_padding=&#8221;30px|30px|30px|80px|false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Sommario<\/h2>\n<p>1 &#8211; <a href=\"#titre1\">Patente nautica per la navigazione costiera<\/a><br \/>\n2 &#8211; <a href=\"#titre2\">La patenta nautica alturiera<\/a><br \/>\n3 &#8211; <a href=\"#titre3\">E navigare all\u2019estero?<\/a>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraphe 1&#8243; module_id=&#8221;titre1&#8243; _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;50px||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>1. Patente nautica per la navigazione costiera<\/h2>\n<p><strong>La patente nautica per la navigazione costiera, che dal 2008 \u00e8 meglio nota come \u201cpatente nautica da diporto per la navigazione costiera\u201d<\/strong>, \u00e8 un documento che abilita alla navigazione in mare. Consente dai 16 anni in su di guidare un motoscafo da diporto con un motore avente una potenza superiore a 6 CV (4,5 KW). Non \u00e8 prevista una potenza massima. Con questa patente \u00e8 possibile guidare un motoscafo da 6 CV o 250 CV o perfino da 500 CV o pi\u00f9! Non vi sono limiti di dimensioni, l\u2019imbarcazione pu\u00f2 misurare 7 o 70 metri, la patente \u00e8 sempre la stessa. Consente anche l\u2019uso di una radio VHF in acque territoriali francesi, di navigare su laghi e specchi d\u2019acqua chiusi, nonch\u00e9 di pilotare una moto d\u2019acqua.<br \/>Con la patente nautica per la navigazione costiera \u00e8 possibile spostarsi fino a 6 miglia da un riparo. Che cos\u2019\u00e8 un riparo? \u00c8 un luogo protetto in cui rifugiarsi insieme alla propria barca ed al proprio equipaggio in caso di forti mareggiate, tempeste, ecc. Il riparo pu\u00f2 essere un porto, una baia, un\u2019isola e persino la barca stessa se si naviga con il relativo tender (gommone\/imbarcazione di servizio). Il concetto di riparo appena descritto consente in taluni casi una distanza reale di 12 miglia. Se un porto o un\u2019isola si trovano infatti a 12 miglia dal porto da cui si parte, \u00e8 possibile recarvisi poich\u00e9 si trova a met\u00e0 strada dal punto di partenza e dal punto di arrivo, cio\u00e8 a 6 miglia!<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraphe 1&#8243; module_id=&#8221;titre2&#8243; _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;50px||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>2. La patenta nautica alturiera<\/h2>\n<p><strong>Se si desidera navigare per oltre 6 miglia da un riparo, la patente nautica costiera non basta pi\u00f9, bisogna essere in possesso dell\u2019estensione alturiera, comunemente nota come patente nautica alturiera<\/strong>. Come suggerisce il nome stesso, si tratta di un\u2019estensione della patente nautica costiera, quindi prima di tutto \u00e8 necessario essere gi\u00e0 in possesso della patente nautica costiera. Con questa estensione, che non \u00e8 soggetta a limiti di distanza, \u00e8 possibile attraversare perfino l\u2019Atlantico!<\/p>\n<p>Superare per\u00f2 l\u2019esame della patente nautica alturiera non \u00e8 solo una questione di distanza, il documento garantisce di essere in possesso di solide competenze marittime: decifrare una carta nautica, prevedere le maree, tenere conto delle correnti, dei venti, della declinazione magnetica, con una mappa cartacea, una bussola e una squadra! Tramite questa estensione \u00e8 possibile navigare anche in caso di guasto della strumentazione elettronica, e acquisire conoscenze pi\u00f9 tradizionali e scientifiche rispetto a quelle relative al permesso nautico costiero. L\u2019esame per la patente nautica costiera consiste in un test con domande a risposta multipla e una prova pratica. L\u2019esame per la patente nautica alturiera, invece, \u00e8 di stampo nettamente diverso: \u00e8 unicamente teorico, consiste in un esercizio di navigazione con carta nautica giornaliera, un secondo esercizio di navigazione con carta nautica notturna (1 ora e 30 min. totali), un calcolo delle maree, ed infine un test con 5 domande a risposta multipla che riguardano ausili elettronici, meteo e dispositivi di sicurezza. <strong>Davvero avvincente!<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraphe 1&#8243; module_id=&#8221;titre3&#8243; _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;50px||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>3. E navigare all\u2019estero?<\/h2>\n<p>La patente nautica costiera e l\u2019estensione alturiera sono patenti francesi per imbarcazioni da diporto le cui prerogative sono valide all\u2019estero se si naviga con un\u2019imbarcazione battente bandiera francese. Navigando all\u2019estero con una barca straniera bisogna ovviamente controllare le normative presso le autorit\u00e0 dei paesi interessati.<\/p>\n<p><strong>Bisogna sapere che in Francia i seguenti organismi possono costantemente effettuare controlli: l\u2019ente francese degli Affari Marittimi, la Guardia costiera francese o la Dogana francese<\/strong>. \u00c8 per\u00f2 vero che durante l\u2019alta stagione vengono effettuati un numero di controlli pi\u00f9 alto. Sono previste sanzioni per vari tipi d\u2019infrazioni: la patente pu\u00f2 essere ritirata temporaneamente o definitivamente in caso di negligenza grave che comprometta la sicurezza delle persone a bordo (ad es. velocit\u00e0 eccessiva); in caso di inosservanza delle norme (ad es. Codice delle vie di navigazione); oppure in caso di ebbrezza o di consumo di sostanze stupefacenti.<br \/>Possono anche essere emesse contravvenzioni se si guida privi di patente nautica (1.500 \u20ac), se si guida nonostante il ritiro della patente (1.500 \u20ac), se si pratica guida accompagnata senza averla previamente dichiarata (150 \u20ac), se si supera il termine per presentare la documentazione amministrativa richiesta (750 \u20ac).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sommario 1 &#8211; Patente nautica per la navigazione costiera 2 &#8211; La patenta nautica alturiera 3 &#8211; E navigare all\u2019estero?1. Patente nautica per la navigazione costiera La patente nautica per la navigazione costiera, che dal 2008 \u00e8 meglio nota come \u201cpatente nautica da diporto per la navigazione costiera\u201d, \u00e8 un documento che abilita alla navigazione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[314],"tags":[],"class_list":["post-9932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sicurezza-e-normative"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quali sono i limiti della patente nautica per la navigazione costiera? - Band of Boats<\/title>\n<meta name=\"description\" content=\"Scopri quali sono i limiti del permesso costiero e quali sono i vantaggi di passare la tua licenza offshore - Band of Boats\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quali sono i limiti della patente nautica per la navigazione costiera? - Band of Boats\" \/>\n<meta property=\"og:description\" content=\"Scopri quali sono i limiti del permesso costiero e quali sono i vantaggi di passare la tua licenza offshore - Band of Boats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/\" \/>\n<meta property=\"og:site_name\" content=\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-12T13:57:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T08:56:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/03\/limite-permis-cotier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"headline\":\"Quali sono i limiti della patente nautica per la navigazione costiera?\",\"datePublished\":\"2019-07-12T13:57:16+00:00\",\"dateModified\":\"2021-11-26T08:56:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/\"},\"wordCount\":912,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/limite-permis-cotier.jpg\",\"articleSection\":[\"Sicurezza e normative\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/\",\"name\":\"Quali sono i limiti della patente nautica per la navigazione costiera? - Band of Boats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/limite-permis-cotier.jpg\",\"datePublished\":\"2019-07-12T13:57:16+00:00\",\"dateModified\":\"2021-11-26T08:56:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"description\":\"Scopri quali sono i limiti del permesso costiero e quali sono i vantaggi di passare la tua licenza offshore - Band of Boats\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/limite-permis-cotier.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/limite-permis-cotier.jpg\",\"width\":1024,\"height\":680,\"caption\":\"Les limites du permis c\u00f4tier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quali sono i limiti della patente nautica per la navigazione costiera?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/\",\"name\":\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quali sono i limiti della patente nautica per la navigazione costiera? - Band of Boats","description":"Scopri quali sono i limiti del permesso costiero e quali sono i vantaggi di passare la tua licenza offshore - Band of Boats","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/","og_locale":"it_IT","og_type":"article","og_title":"Quali sono i limiti della patente nautica per la navigazione costiera? - Band of Boats","og_description":"Scopri quali sono i limiti del permesso costiero e quali sono i vantaggi di passare la tua licenza offshore - Band of Boats","og_url":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/","og_site_name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","article_published_time":"2019-07-12T13:57:16+00:00","article_modified_time":"2021-11-26T08:56:46+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/03\/limite-permis-cotier.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#article","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/"},"author":{"name":"admin","@id":"https:\/\/blog.bandofboats.com\/it\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"headline":"Quali sono i limiti della patente nautica per la navigazione costiera?","datePublished":"2019-07-12T13:57:16+00:00","dateModified":"2021-11-26T08:56:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/"},"wordCount":912,"commentCount":0,"image":{"@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/03\/limite-permis-cotier.jpg","articleSection":["Sicurezza e normative"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/","url":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/","name":"Quali sono i limiti della patente nautica per la navigazione costiera? - Band of Boats","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#primaryimage"},"image":{"@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/03\/limite-permis-cotier.jpg","datePublished":"2019-07-12T13:57:16+00:00","dateModified":"2021-11-26T08:56:46+00:00","author":{"@id":"https:\/\/blog.bandofboats.com\/it\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"description":"Scopri quali sono i limiti del permesso costiero e quali sono i vantaggi di passare la tua licenza offshore - Band of Boats","breadcrumb":{"@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#primaryimage","url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/03\/limite-permis-cotier.jpg","contentUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/03\/limite-permis-cotier.jpg","width":1024,"height":680,"caption":"Les limites du permis c\u00f4tier"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.bandofboats.com\/it\/quali-sono-i-limiti-della-patente-nautica-per-la-navigazione-costiera-quali-sono-i-controlli-e-le-sanzioni-in-caso-di-inadempienza-perche-passare-lesame-per-la-patente-nautica-alturiera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.bandofboats.com\/it\/"},{"@type":"ListItem","position":2,"name":"Quali sono i limiti della patente nautica per la navigazione costiera?"}]},{"@type":"WebSite","@id":"https:\/\/blog.bandofboats.com\/it\/#website","url":"https:\/\/blog.bandofboats.com\/it\/","name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.bandofboats.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.bandofboats.com\/it\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/posts\/9932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/comments?post=9932"}],"version-history":[{"count":0,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/posts\/9932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/media\/9123"}],"wp:attachment":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/media?parent=9932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/categories?post=9932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/tags?post=9932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}