{"id":8507,"date":"2018-06-13T15:00:43","date_gmt":"2018-06-13T13:00:43","guid":{"rendered":"https:\/\/www.bandofboats.com\/?p=8507"},"modified":"2021-11-26T11:36:00","modified_gmt":"2021-11-26T10:36:00","slug":"propulsore-trasversale-quale-scegliere","status":"publish","type":"post","link":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/","title":{"rendered":"Il propulsore trasversale: quale scegliere?"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Chap\u00f4 de l&#8217;article&#8221; _builder_version=&#8221;4.11.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Source Sans Pro|600|||||||&#8221; text_text_color=&#8221;#063462&#8243; text_font_size=&#8221;18px&#8221; custom_padding=&#8221;30px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Alcune attrezzature non sono obbligatorie, ma la loro capacit\u00e0 di <strong>migliorare l\u2019esperienza di navigazione<\/strong> le rende molto preziose.<\/p>\n<p>\u00c8 il caso del <strong>propulsore trasversale<\/strong>, che rende un gioco da ragazzi accostare la propria barca o salpare agilmente da un pontile. Quando siete alla guida della vostra auto, siete in grado di parcheggiarla perfettamente grazie alle vostra bravura ma anche (diciamo, soprattutto\u2026) grazie al servosterzo, non \u00e8 vero? Con la vostra barca \u00e8 lo stesso: <strong>la presenza di un propulsore trasversale facilita le manovre pi\u00f9 delicate in porto<\/strong>. Fateci un pensiero!<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Sommaire&#8221; _builder_version=&#8221;4.11.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Source Sans Pro|600|||||||&#8221; text_line_height=&#8221;2em&#8221; link_text_color=&#8221;#3e6a91&#8243; background_color=&#8221;#fef9f5&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;50px||0px||false|false&#8221; custom_padding=&#8221;30px|30px|30px|80px|false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Riassunto<\/h2>\n<p>1 &#8211; <a href=\"#titre1\">Che cos\u2019\u00e8 un propulsore trasversale?<\/a><br \/>\n2 &#8211; <a href=\"#titre2\">Quale tipo di propulsore trasversale devo scegliere?<\/a>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraphe 1&#8243; module_id=&#8221;titre1&#8243; _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>1. Che cos\u2019\u00e8 un propulsore trasversale?<\/h2>\n<p>Si tratta di <strong>un\u2019elica posizionata a prua della barca<\/strong> in senso trasversale, pilotata dal timone tramite un potente motore elettrico. <strong>Questo motore permette di spostarla a babordo o a tribordo<\/strong>. Il posizionamento \u00e8 cruciale per garantire prestazioni ottimali: l\u2019elica deve trovarsi sotto la linea di galleggiamento, rimanendo il pi\u00f9 possibile vicina alla trave (vedi figura qui sotto).<\/p>\n<p>Se la vostra <strong>barca \u00e8 lunga oltre 7 metri<\/strong>, Band of Boats vi consiglia di investire in un propulsore trasversale per manovrare la vostra imbarcazione in modo facile e sicuro. Alcuni tipi di propulsori si installano a poppa anzich\u00e9 a <strong>prua<\/strong>; montandoli entrambi, sarete in grado di fare ruotare la vostra barca a 360\u00b0 anche in spazi estremamente ridotti, proprio come dei professionisti!<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraphe 1&#8243; module_id=&#8221;titre2&#8243; _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>2. Quale tipo di propulsore trasversale devo scegliere?<\/h2>\n<p>Per scegliere il propulsore trasversale pi\u00f9 adatto alla vostra barca, dovrete valutare alcuni elementi essenziali fra cui:<\/p>\n<ol>\n<li>Qual \u00e8 la <strong>resistenza al vento<\/strong> della vostra barca? La resistenza al vento corrisponde a tutti materiali (ad eccezione delle vele) che compongono la barca e si trovano al di sopra della linea di navigazione. L\u2019insieme di questi materiali genera una resistenza passiva al vento, creando turbolenze. Se questo parametro \u00e8 elevato, scegliete un propulsore progettato per barche di taglia superiore alla vostra, e viceversa.<\/li>\n<li>In che <strong>tipo di porto<\/strong> vi trovate? Per valutare la potenza necessaria dovrete considerare la forza del vento medio dominante, le correnti e l\u2019accesso al vostro porto.<\/li>\n<li>Che <strong>tipo di barca<\/strong> possedete? Ad esempio, un modello da 40 piedi a fondo \u201cpiatto\u201d e poca profondit\u00e0 sotto il propulsore riduce le possibilit\u00e0 di installazione.<\/li>\n<li>Qual \u00e8 il vostro <strong>budget?<\/strong><\/li>\n<\/ol>\n<p>Per affinare la vostra ricerca, Band of Boats vi illustra in dettaglio i diversi tipi di propulsore trasversale esistenti indicando vantaggi e svantaggi di ciascuno. A voi la scelta del pi\u00f9 adatto!<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraphe 1&#8243; _builder_version=&#8221;4.11.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Avete fatto la vostra scelta? Non vi resta che condividere le vostre esperienze di manovra con la comunit\u00e0 Band of Boats. I vostri suggerimenti sono sempre ben accetti!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcune attrezzature non sono obbligatorie, ma la loro capacit\u00e0 di migliorare l\u2019esperienza di navigazione le rende molto preziose. \u00c8 il caso del propulsore trasversale, che rende un gioco da ragazzi accostare la propria barca o salpare agilmente da un pontile. Quando siete alla guida della vostra auto, siete in grado di parcheggiarla perfettamente grazie alle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\r\n<p>Beaucoup d\u2019\u00e9quipements ne sont, certes, pas obligatoires, mais leur capacit\u00e9 \u00e0 <strong>am\u00e9liorer l\u2019exp\u00e9rience de navigation<\/strong>les rendent pr\u00e9cieux. C\u2019est le cas du <strong>propulseur d\u2019\u00e9trave<\/strong>. Accoster son bateau ou quitter le quai deviennent un jeu d\u2019enfant gr\u00e2ce \u00e0 lui. Vous ma\u00eetrisez les cr\u00e9neaux en voiture gr\u00e2ce \u00e0 votre habilet\u00e9 mais aussi (voire beaucoup ...) gr\u00e2ce \u00e0 la direction assist\u00e9e, n\u2019est-ce pas ? C\u2019est pareil \u00e0 bord de votre bateau, la pr\u00e9sence d\u2019un propulseur d\u2019\u00e9trave <strong>facilite les man\u0153uvres d\u00e9licates au port<\/strong>, pensez-y !   <\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:heading -->\r\n<h2>QU'EST-CE QU'UN PROPULSEUR D'ETRAVE?<\/h2>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Il s\u2019agit d\u2019une <strong>h\u00e9lice plac\u00e9e \u00e0 l\u2019avant du bateau<\/strong> en travers de la marche, et pilot\u00e9e depuis le poste de barre via un moteur \u00e9lectrique puissant. Elle permet de <strong>d\u00e9placer l\u2019\u00e9trave \u00e0 b\u00e2bord ou tribord<\/strong>.  Pour une performance optimale, son positionnement est crucial : l\u2019h\u00e9lice doit \u00eatre sous la ligne de flottaison tout en \u00e9tant le plus pr\u00e8s de l\u2019\u00e9trave (voir sch\u00e9ma ci-dessous).<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:image -->\r\n<figure class=\"wp-block-image\"><img src=\"https:\/\/www.bandofboats.com\/medias\/images\/Blog\/article%20propulseur\/PROPULSEUR%20V2.jpg\" alt=\"\"\/><\/figure>\r\n<!-- \/wp:image -->\r\n\r\n<!-- wp:paragraph -->\r\n<p> Si votre <strong>bateau<\/strong> fait <strong>plus de 7 m\u00e8tres<\/strong> de long, Band of Boats vous recommande d\u2019investir dans un propulseur d\u2019\u00e9trave pour man\u0153uvrer ais\u00e9ment et en toute s\u00e9curit\u00e9. Certains propulseurs, dit de <strong>poupe<\/strong>, s\u2019installent \u00e0 l\u2019<strong>arri\u00e8re<\/strong>. En \u00e9quipant votre bateau de ces 2 mod\u00e8les, vous serez capable de faire pivoter votre bateau de 360\u00b0 dans un espace restreint comme un pro !<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:heading -->\r\n<h2>QUEL TYPE DE PROPULSEUR D'ETRAVE POUR MON BATEAU?<\/h2>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Pour bien choisir son propulseur d\u2019\u00e9trave, quelques \u00e9l\u00e9ments essentiels sont \u00e0 prendre en compte, les voici :<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:list {\"ordered\":true} -->\r\n<ol><li>Quel <strong>fardage<\/strong> avez-vous? : Il s\u2019agit de tout ce qui (\u00e0 l\u2019exception des voiles), fait partie du bateau et se trouve au-dessus de la surface de l\u2019eau. Le fardage offre une r\u00e9sistance passive au vent et cr\u00e9\u00e9 des turbulences. Si votre fardage est important, choisissez un propulseur destin\u00e9 \u00e0 des bateaux de taille sup\u00e9rieure au v\u00f4tre et inversement.<\/li><li>Dans quel <strong>type de port<\/strong> \u00eates-vous? : vous devez consid\u00e9rer la force du vent moyen dominant, les courants, l\u2019acc\u00e8s \u00e0 votre port pour \u00e9valuer la puissance n\u00e9cessaire.<\/li><li>Quel <strong>type de bateau<\/strong> avez-vous ? Par exemple, un mod\u00e8le de 40 pieds \u00e0 fond \u00ab plat \u00bb et peu de profondeur sous l\u2019\u00e9trave r\u00e9duit les possibilit\u00e9s d\u2019installation.<\/li><li>Quel est votre <strong>budget<\/strong> ? <\/li><\/ol>\r\n<!-- \/wp:list -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Pour affiner votre choix, Band of Boats vous d\u00e9crit en d\u00e9tail les diff\u00e9rents types de propulseurs d\u2019\u00e9trave existants et vous \u00e9num\u00e8re les atouts et inconv\u00e9nients de chacun, \u00e0 vous de s\u00e9lectionner le plus adapt\u00e9 !<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:table -->\r\n<table class=\"wp-block-table\"><tbody><tr><td><strong>TYPE<\/strong><\/td><td><strong>C'EST QUOI?<\/strong>                       <\/td><td><strong>   LES +<\/strong>  <\/td><td><strong>LES -<\/strong><\/td><\/tr><tr><td><strong>A tunnel<\/strong><\/td><td>Un tuyau traverse la coque d'un bord \u00e0 l'autre avec l'h\u00e9lice \u00e0 l'int\u00e9rieur et le moteur au-dessus.<\/td><td> Installation facile <\/td><td>Inadapt\u00e9 pour les car\u00e8nes <br>trop plates<br>Moins performant qu'un r\u00e9tractable<br>Risques en cas d'objets pr\u00e9sents \u00e0 proximit\u00e9 de l'h\u00e9lice<\/td><\/tr><tr><td><strong>                      R\u00e9tractable<\/strong> <\/td><td>L'h\u00e9lice est sur un v\u00e9rin. <br>Elle sort quand on en a besoin etdispara\u00eet dans la coque hors <br>utilisation<\/td><td> L'h\u00e9lice reste prot\u00e9g\u00e9e <br>Surface de coque reste identique<br>Ne perturbe pas la navigation<\/td><td>Meilleure performance    <br>Installation complexe: n\u00e9cessite une d\u00e9coupe sp\u00e9cifique et un renfort structurel de la coque.<br>Risques de pannes m\u00e9caniques entr\u00e9e \/ sortie<\/td><\/tr><tr><td><strong>Externe<\/strong><\/td><td>Le moteur et l'h\u00e9lice sont dans <br>un bloc \u00e9tanche immerg\u00e9 sous <br>l'\u00e9trave.<\/td><td>Installation tr\u00e8s facile<br>Possibilit\u00e9 de le fixer le plus en avant de l'\u00e9trave<br>performance am\u00e9lior\u00e9e<\/td><td>Perturbe les performances \u00e0 la voile<br>Augmente la consommation au moteur<\/td><\/tr><tr><td><strong>A jet d'eau<\/strong><\/td><td>Une pompe aspire l'eau sur le bord oppos\u00e9, la stocke dans un r\u00e9cipient embarqu\u00e9 et la rejette de l'autre c\u00f4t\u00e9.<\/td><td>Solution de secours si impossibilit\u00e9 d'installer les autres types.<br>Solution la plus s\u00e9curisante: aucun risque d'aspirer des cordages flottants<\/td><td>Puissance \u00e9lectrique importante<br>Co\u00fbt \u00e9lev\u00e9<\/td><\/tr><\/tbody><\/table>\r\n<!-- \/wp:table -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Votre choix est fait ? Il ne vous reste qu\u2019\u00e0 <strong>partager vos exp\u00e9riences<\/strong> de man\u0153uvres avec l\u2019ensemble de la communaut\u00e9 Band of Boats. Vos avis nous sont toujours pr\u00e9cieux.  <\/p>\r\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[326],"tags":[],"class_list":["post-8507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comprare-barca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il propulsore trasversale: quale scegliere? - Band of Boats<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il propulsore trasversale: quale scegliere? - Band of Boats\" \/>\n<meta property=\"og:description\" content=\"Alcune attrezzature non sono obbligatorie, ma la loro capacit\u00e0 di migliorare l\u2019esperienza di navigazione le rende molto preziose. \u00c8 il caso del propulsore trasversale, che rende un gioco da ragazzi accostare la propria barca o salpare agilmente da un pontile. Quando siete alla guida della vostra auto, siete in grado di parcheggiarla perfettamente grazie alle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/\" \/>\n<meta property=\"og:site_name\" content=\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-13T13:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T10:36:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2018\/06\/propulseur-etrave.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"841\" \/>\n\t<meta property=\"og:image:height\" content=\"459\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"headline\":\"Il propulsore trasversale: quale scegliere?\",\"datePublished\":\"2018-06-13T13:00:43+00:00\",\"dateModified\":\"2021-11-26T10:36:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/\"},\"wordCount\":675,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/propulseur-etrave.jpg\",\"articleSection\":[\"Comprare una barca\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/\",\"name\":\"Il propulsore trasversale: quale scegliere? - Band of Boats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/propulseur-etrave.jpg\",\"datePublished\":\"2018-06-13T13:00:43+00:00\",\"dateModified\":\"2021-11-26T10:36:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/propulseur-etrave.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/propulseur-etrave.jpg\",\"width\":841,\"height\":459},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/propulsore-trasversale-quale-scegliere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il propulsore trasversale: quale scegliere?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/\",\"name\":\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/it\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il propulsore trasversale: quale scegliere? - Band of Boats","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/","og_locale":"it_IT","og_type":"article","og_title":"Il propulsore trasversale: quale scegliere? - Band of Boats","og_description":"Alcune attrezzature non sono obbligatorie, ma la loro capacit\u00e0 di migliorare l\u2019esperienza di navigazione le rende molto preziose. \u00c8 il caso del propulsore trasversale, che rende un gioco da ragazzi accostare la propria barca o salpare agilmente da un pontile. Quando siete alla guida della vostra auto, siete in grado di parcheggiarla perfettamente grazie alle [&hellip;]","og_url":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/","og_site_name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","article_published_time":"2018-06-13T13:00:43+00:00","article_modified_time":"2021-11-26T10:36:00+00:00","og_image":[{"width":841,"height":459,"url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2018\/06\/propulseur-etrave.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#article","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/"},"author":{"name":"admin","@id":"https:\/\/blog.bandofboats.com\/it\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"headline":"Il propulsore trasversale: quale scegliere?","datePublished":"2018-06-13T13:00:43+00:00","dateModified":"2021-11-26T10:36:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/"},"wordCount":675,"commentCount":0,"image":{"@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2018\/06\/propulseur-etrave.jpg","articleSection":["Comprare una barca"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/","url":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/","name":"Il propulsore trasversale: quale scegliere? - Band of Boats","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#primaryimage"},"image":{"@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2018\/06\/propulseur-etrave.jpg","datePublished":"2018-06-13T13:00:43+00:00","dateModified":"2021-11-26T10:36:00+00:00","author":{"@id":"https:\/\/blog.bandofboats.com\/it\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"breadcrumb":{"@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#primaryimage","url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2018\/06\/propulseur-etrave.jpg","contentUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2018\/06\/propulseur-etrave.jpg","width":841,"height":459},{"@type":"BreadcrumbList","@id":"https:\/\/blog.bandofboats.com\/it\/propulsore-trasversale-quale-scegliere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.bandofboats.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il propulsore trasversale: quale scegliere?"}]},{"@type":"WebSite","@id":"https:\/\/blog.bandofboats.com\/it\/#website","url":"https:\/\/blog.bandofboats.com\/it\/","name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.bandofboats.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.bandofboats.com\/it\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/posts\/8507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/comments?post=8507"}],"version-history":[{"count":0,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/posts\/8507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/media\/16550"}],"wp:attachment":[{"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/media?parent=8507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/categories?post=8507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/it\/wp-json\/wp\/v2\/tags?post=8507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}