{"id":6179,"date":"2017-12-05T12:00:58","date_gmt":"2017-12-05T11:00:58","guid":{"rendered":"http:\/\/blog.heycaptain.fr\/?p=6179"},"modified":"2021-11-26T17:03:06","modified_gmt":"2021-11-26T16:03:06","slug":"pratique-sports-nautiques","status":"publish","type":"post","link":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/","title":{"rendered":"Les meilleurs spots pour la pratique de sports nautiques"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.22&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.11.1&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbChap\u00f4 de l&rsquo;article\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbSource Sans Pro|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#063462&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_padding=\u00a0\u00bb30px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\">Amateurs de sensations fortes, on a pr\u00e9par\u00e9 pour vous une s\u00e9lection des meilleurs et des plus beaux endroits pour la pratique des sports nautiques.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbSommaire\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbSource Sans Pro|600|||||||\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb link_text_color=\u00a0\u00bb#3e6a91&Prime; background_color=\u00a0\u00bb#fef9f5&Prime; module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|80px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Sommaire<\/h2>\n<p>1 &#8211; <a href=\"#titre1\">Les sports nautiques en France<\/a><br \/>\n2 &#8211; <a href=\"#titre2\">Les sports nautiques en Gr\u00e8ce<\/a><br \/>\n3 &#8211; <a href=\"#titre3\">Les sports nautiques ailleurs<\/a>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbParagraphe 1&Prime; module_id=\u00a0\u00bbtitre1&Prime; _builder_version=\u00a0\u00bb4.11.1&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>1. Les sports nautiques en France<\/h2>\n<p>En France, vous pourrez pratiquer du kitesurf au Languedoc-Roussillon, au lac de Vassivi\u00e8re, dans les c\u00f4tes landaises et en Corse.<\/p>\n<p>Pour pratiquer le char \u00e0 voile c\u2019est l\u2019id\u00e9al, dans la baie de Somme, la c\u00f4te normande, la c\u00f4te bretonne et vend\u00e9enne.<\/p>\n<p>Pour plonger en France, allez voir les eaux cristallines de la Corse et ses criques sauvages. Pour faire du kayak en mer rien de mieux que de se rendre \u00e0 Belle-\u00eele en Mer, dans le Golfe du Morbihan. Dans le sud, pr\u00e8s de Marseille dans les calanques, et \u00e0 l\u2019\u00eele de Frioul. <\/p>\n<p>Pour faire du surf on vous recommande la c\u00f4te basque, allez \u00e0 Mundaka en plein coeur de la r\u00e9serve naturelle Urdabai, l\u2019un des spots de surf les plus renomm\u00e9. Pour les experts, rendez-vous \u00e0 la plage Laidatxu.[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbParagraphe 1&Prime; module_id=\u00a0\u00bbtitre2&Prime; _builder_version=\u00a0\u00bb4.11.1&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>2. Les sports nautiques en Gr\u00e8ce<\/h2>\n<p>Si vous partez en vacances en Gr\u00e8ce, c\u2019est l\u2019endroit id\u00e9al pour pratiquer la planche \u00e0 voile, le kitesurf, le wakeboard et la plong\u00e9e.<\/p>\n<p>Les Cyclades, les \u00eeles Ioniennes et Sporades sont les lieux parfaits pour la pratique de plong\u00e9e. Vous pourrez y observer et prendre des clich\u00e9s des bateaux naufrag\u00e9s et des grottes sous-marines.<\/p>\n<p>Si vous \u00eates plus amateur de surf et Kitesurf, Vouliagmeni et Vari, Anavyssos et Lavrion, Horefto \u00e0 P\u00e9lion sont les meilleurs spots. Si vous n\u2019avez pas votre propre \u00e9quipement vous pourrez en louer directement sur place.<\/p>\n<p>En Gr\u00e8ce le ski nautique peut se pratiquer sur toutes les plages, d\u2019autant plus qu\u2019il y de nombreuses associations et clubs pour apprendre si vous le souhait\u00e9. Par ailleurs, le wakeboard se pratique \u00e0 Attique, \u00e0 la \u201cRiviera\u201d ath\u00e9nienne Anavyssos, \u00e0 Lavrion, Varkiza, Galazia Akti au Marathon. A Paros \u00e0 Chryssi Akti (Golden Beach).[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbParagraphe 1&Prime; module_id=\u00a0\u00bbtitre3&Prime; _builder_version=\u00a0\u00bb4.11.1&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>3. Les sports nautiques ailleurs<\/h2>\n<p>Si vous d\u00e9cidez de franchir la fronti\u00e8re, aller en Espagne sur la Costa de la Luz, \u00e0 la plage Tarifa pour pratiquer de la planche \u00e0 voile et sur la plage de Bolonia pour faire du kitesurf. Et comme sport de plong\u00e9 sympa on vous conseille El Hierro aux \u00eeles Canaries.<\/p>\n<p>Amoureux de paysage paradisiaques et idylliques, allez plonger en Nouvelle Cal\u00e9donie pour d\u00e9couvrir la barri\u00e8re de corail et en Polyn\u00e9sie pour nager avec les tortues, les raies et m\u00eame les requins!<\/p>\n<p>Cependant, ne vous aventurez pas seul ! Assurez-vous que la pratique du sport est bien autoris\u00e9 et n\u2019oubliez pas pour votre s\u00e9curit\u00e9 de vous prot\u00e9gez.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amateurs de sensations fortes, on a pr\u00e9par\u00e9 pour vous une s\u00e9lection des meilleurs et des plus beaux endroits pour la pratique des sports nautiques.Sommaire 1 &#8211; Les sports nautiques en France 2 &#8211; Les sports nautiques en Gr\u00e8ce 3 &#8211; Les sports nautiques ailleurs1. Les sports nautiques en France En France, vous pourrez pratiquer du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>Amateurs de sensations fortes, on a pr\u00e9par\u00e9 pour vous une s\u00e9lection des meilleurs et des plus beaux endroits pour la pratique des sports nautiques.<!--more--><\/p><p>Si vous partez en vacances en Gr\u00e8ce, c\u2019est l\u2019endroit id\u00e9al pour pratiquer la planche \u00e0 voile, le kitesurf, le wakeboard et la plong\u00e9e.<\/p><p>Les Cyclades, les \u00eeles Ioniennes et Sporades sont les lieux parfaits pour la pratique de plong\u00e9e. Vous pourrez y observer et prendre des clich\u00e9s des bateaux naufrag\u00e9s et des grottes sous-marines.<br \/>Si vous \u00eates plus amateur de surf et Kitesurf, Vouliagmeni et Vari, Anavyssos et Lavrion, Horefto \u00e0 P\u00e9lion sont les meilleurs spots. Si vous n\u2019avez pas votre propre \u00e9quipement vous pourrez en louer directement sur place.<\/p><p>En Gr\u00e8ce le ski nautique peut se pratiquer sur toutes les plages, d\u2019autant plus qu\u2019il y de nombreuses associations et clubs pour apprendre si vous le souhait\u00e9.<br \/>Par ailleurs, le wakeboard se pratique \u00e0 Attique, \u00e0 la \u201cRiviera\u201d ath\u00e9nienne Anavyssos, \u00e0 Lavrion, Varkiza, Galazia Akti au Marathon. A Paros \u00e0 Chryssi Akti (Golden Beach).<\/p><p>En France, vous pourrez pratiquer du kitesurf au Languedoc-Roussillon, au lac de vassivi\u00e8re, dans les c\u00f4tes landaises et en Corse.<\/p><p>Pour pratiquer le char \u00e0 voile c\u2019est l\u2019id\u00e9al, dans la baie de Somme, la c\u00f4te normande, la c\u00f4te bretonne et vend\u00e9enne.<\/p><p>Pour plonger en France, allez voir les eaux cristallines de la Corse et ses criques sauvages. Pour faire du kayak en mer rien de mieux que de se rendre \u00e0 Belle-\u00eele en Mer, dans le Golfe du Morbihan. Dans le sud, pr\u00e8s de Marseille dans les calanques, et \u00e0 l\u2019\u00eele de Frioul.<br \/>Pour faire du surf on vous recommande la c\u00f4te basque, allez \u00e0 Mundaka en plein coeur de la r\u00e9serve naturelle Urdabai, l\u2019un des spots de surf les plus renomm\u00e9. Pour les experts, rendez-vous \u00e0 la plage Laidatxu.<\/p><p>Si vous d\u00e9cidez de franchir la fronti\u00e8re, aller en Espagne sur la Costa de la Luz, \u00e0 la plage Tarifa pour pratiquer de la planche \u00e0 voile et sur la plage de Bolonia pour faire du kitesurf. Et comme sport de plong\u00e9 sympa on vous conseille El Hierro aux \u00eeles Canaries.<br \/>Amoureux de paysage paradisiaques et idylliques, allez plonger en Nouvelle Cal\u00e9donie pour d\u00e9couvrir la barri\u00e8re de corail et en Polyn\u00e9sie pour nager avec les tortues, les raies et m\u00eame les requins!<\/p><p>Cependant, ne vous aventurez pas seul ! Assurez-vous que la pratique du sport est bien autoris\u00e9 et n\u2019oubliez pas pour votre s\u00e9curit\u00e9 de vous prot\u00e9gez.<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[282],"tags":[],"class_list":["post-6179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destinations-ou-naviguer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les meilleurs spots pour la pratique de sports nautiques - Band of Boats<\/title>\n<meta name=\"description\" content=\"Vous en avez marre des balades tranquilles en bateau ? On vous propose nos meilleurs spots pour la pratique des sports nautiques !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les meilleurs spots pour la pratique de sports nautiques - Band of Boats\" \/>\n<meta property=\"og:description\" content=\"Vous en avez marre des balades tranquilles en bateau ? On vous propose nos meilleurs spots pour la pratique des sports nautiques !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-05T11:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T16:03:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2017\/06\/wakebooard.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"headline\":\"Les meilleurs spots pour la pratique de sports nautiques\",\"datePublished\":\"2017-12-05T11:00:58+00:00\",\"dateModified\":\"2021-11-26T16:03:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/\"},\"wordCount\":716,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/wakebooard.jpg\",\"articleSection\":[\"Destinations o\u00f9 naviguer\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/\",\"name\":\"Les meilleurs spots pour la pratique de sports nautiques - Band of Boats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/wakebooard.jpg\",\"datePublished\":\"2017-12-05T11:00:58+00:00\",\"dateModified\":\"2021-11-26T16:03:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"description\":\"Vous en avez marre des balades tranquilles en bateau ? On vous propose nos meilleurs spots pour la pratique des sports nautiques !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/wakebooard.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/wakebooard.jpg\",\"width\":800,\"height\":533,\"caption\":\"image sports nautiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/pratique-sports-nautiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les meilleurs spots pour la pratique de sports nautiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/\",\"name\":\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les meilleurs spots pour la pratique de sports nautiques - Band of Boats","description":"Vous en avez marre des balades tranquilles en bateau ? On vous propose nos meilleurs spots pour la pratique des sports nautiques !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Les meilleurs spots pour la pratique de sports nautiques - Band of Boats","og_description":"Vous en avez marre des balades tranquilles en bateau ? On vous propose nos meilleurs spots pour la pratique des sports nautiques !","og_url":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/","og_site_name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","article_published_time":"2017-12-05T11:00:58+00:00","article_modified_time":"2021-11-26T16:03:06+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2017\/06\/wakebooard.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#article","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/"},"author":{"name":"admin","@id":"https:\/\/blog.bandofboats.com\/fr\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"headline":"Les meilleurs spots pour la pratique de sports nautiques","datePublished":"2017-12-05T11:00:58+00:00","dateModified":"2021-11-26T16:03:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/"},"wordCount":716,"commentCount":0,"image":{"@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2017\/06\/wakebooard.jpg","articleSection":["Destinations o\u00f9 naviguer"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/","url":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/","name":"Les meilleurs spots pour la pratique de sports nautiques - Band of Boats","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#primaryimage"},"image":{"@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2017\/06\/wakebooard.jpg","datePublished":"2017-12-05T11:00:58+00:00","dateModified":"2021-11-26T16:03:06+00:00","author":{"@id":"https:\/\/blog.bandofboats.com\/fr\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"description":"Vous en avez marre des balades tranquilles en bateau ? On vous propose nos meilleurs spots pour la pratique des sports nautiques !","breadcrumb":{"@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#primaryimage","url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2017\/06\/wakebooard.jpg","contentUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2017\/06\/wakebooard.jpg","width":800,"height":533,"caption":"image sports nautiques"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.bandofboats.com\/fr\/pratique-sports-nautiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.bandofboats.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les meilleurs spots pour la pratique de sports nautiques"}]},{"@type":"WebSite","@id":"https:\/\/blog.bandofboats.com\/fr\/#website","url":"https:\/\/blog.bandofboats.com\/fr\/","name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.bandofboats.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.bandofboats.com\/fr\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/posts\/6179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/comments?post=6179"}],"version-history":[{"count":0,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/posts\/6179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/media\/6181"}],"wp:attachment":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/media?parent=6179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/categories?post=6179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/tags?post=6179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}