{"id":10754,"date":"2019-10-24T10:44:21","date_gmt":"2019-10-24T08:44:21","guid":{"rendered":"https:\/\/blog.bandofboats.com\/?p=10754"},"modified":"2024-01-22T17:59:51","modified_gmt":"2024-01-22T16:59:51","slug":"essai-bateau-sur-le-sun-odyssey-409","status":"publish","type":"post","link":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/","title":{"rendered":"Essai Bateau sur le Sun Odyssey 409"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbChap\u00f4 de l&rsquo;article\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbSource Sans Pro|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#063462&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_padding=\u00a0\u00bb30px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\">Rempla\u00e7ant le <a href=\"https:\/\/www.bandofboats.com\/fr\/toutes-les-marques\/jeanneau\/sun-odyssey\/sun-odyssey-39-i\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey 39i<\/a>, le <a href=\"https:\/\/www.bandofboats.com\/fr\/toutes-les-marques\/jeanneau\/sun-odyssey\/sun-odyssey-409\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey 409<\/a> de la gamme <a href=\"https:\/\/www.bandofboats.com\/fr\/toutes-les-marques\/jeanneau\/sun-odyssey\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey<\/a>, lanc\u00e9 en 2011, est un croiseur sportif, pens\u00e9 pour \u00eatre men\u00e9 en \u00e9quipage r\u00e9duit. Construit \u00e0 plus de 300 exemplaires et sacr\u00e9 European Yacht of The Year 2011, sa taille et ses commandes ramen\u00e9es vers le barreur m\u2019ont fait choisir ce monocoque pour une nouvelle croisi\u00e8re de 21 jours dans les petites Antilles, l\u2019\u00e9t\u00e9, p\u00e9riode m\u00e9t\u00e9orologiquement mouvement\u00e9e peupl\u00e9e de d\u00e9pressions tropicales\u2026 Je vous donne mon avis \u00e0 travers cet essai bateau r\u00e9dig\u00e9.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbSommaire\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbSource Sans Pro|600|||||||\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb link_text_color=\u00a0\u00bb#3e6a91&Prime; background_color=\u00a0\u00bb#fef9f5&Prime; module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb30px|20px|30px|40px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Sommaire<\/h2>\n<p>1 &#8211; <a href=\"#titre1\">Des lignes tendues<\/a><br \/>\n2 &#8211; <a href=\"#titre2\">Une construction solide<\/a><br \/>\n3 &#8211; <a href=\"#titre3\">Un plan de pont innovant<\/a><br \/>\n4 &#8211; <a href=\"#titre4\">Un int\u00e9rieur clair et de la hauteur sous barrots<\/a><br \/>\n5 &#8211; <a href=\"#titre5\">Syst\u00e8mes<\/a><br \/>\n6 &#8211; <a href=\"#titre6\">En navigation<\/a><br \/>\n7 &#8211; <a href=\"#titre7\">Principales dimensions<\/a><br \/>\n8 &#8211; <a href=\"#titre8\">Conclusion<\/a>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bb1. Des lignes tendues\u00a0\u00bb module_id=\u00a0\u00bbtitre1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>1. Des lignes tendues<\/h2>\n<p>Bouchains saillants, hublots de pont flush, design \u00e9pur\u00e9, Philippe Briand a dessin\u00e9 une car\u00e8ne moderne et fluide pour Jeanneau. 11,98 m de long pour 3,99 m de large, le bateau d\u00e9gage une impression de puissance quand on le regarde du quai. Les deux barres \u00e0 roues d\u00e9gagent un vaste espace dans le cockpit, d\u2019autant que le radeau dispara\u00eet dans un coffre d\u00e9di\u00e9 (ou on rangera aussi la porte d\u2019acc\u00e8s au carr\u00e9). Le tableau arri\u00e8re s\u2019ouvre sur \u2153 environ, conservant deux bonnes assises de part et d\u2019autre. Une douche de pont d\u00e9livrant de l\u2019eau chaude et froide est install\u00e9e \u00e0 tribord.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-20918 aligncenter size-full\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-maquette.jpg\" alt=\"\" width=\"810\" height=\"424\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-maquette.jpg 810w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-maquette-480x251.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 810px, 100vw\" \/><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bb2. Une construction solide\u00a0\u00bb module_id=\u00a0\u00bbtitre2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>2. Une construction solide<\/h2>\n<p>La coque, renforc\u00e9e par un treillis fibre de verre int\u00e9rieur, r\u00e9alis\u00e9e \u00e0 la main, est finie avec un appr\u00eat \u00e9poxy puis un Gelcoat. Le pont est moul\u00e9 par injection avec une \u00e2me en balsa discontinue. Les parties du pont soumises \u00e0 de forts efforts en sont d\u00e9pourvues. La quille est en en fonte d\u2019acier. Le bateau existe en deux versions GTE (tirant d\u2019eau de 2,10 m) et PTE (tirant d\u2019eau de 1,55m). M\u00e2t et b\u00f4me sont en aluminium, une version avec m\u00e2t \u00e0 enrouleur est disponible en option.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-20923 aligncenter size-full\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-navigation.jpg\" alt=\"\" width=\"810\" height=\"424\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-navigation.jpg 810w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-navigation-480x251.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 810px, 100vw\" \/><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.bandofboats.com\/fr\/toutes-les-marques\/jeanneau\/sun-odyssey\/sun-odyssey-409?utm_source=blog&#038;utm_medium=CTA&#038;utm_campaign_article-sun-odyssey-409&Prime; url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbVoir les annonces de Sun Odyssey 409&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb admin_label=\u00a0\u00bbCTA annonces\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#063462&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_text admin_label=\u00a0\u00bb3. Un plan de pont innovant\u00a0\u00bb module_id=\u00a0\u00bbtitre3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>3. Un plan de pont innovant<\/h2>\n<p><strong>Pens\u00e9 pour \u00eatre men\u00e9 par un couple<\/strong>, le Sun Odyssey 409 re\u00e7oit deux winchs au poste de barre (qui peuvent \u00eatre \u00e9lectrifi\u00e9s en option) et deux winchs, plus petits, sur le roof. Pour faciliter les man\u0153uvres, <a href=\"https:\/\/www.bandofboats.com\/fr\/toutes-les-marques\/jeanneau\">Jeanneau<\/a> a ramen\u00e9 en arri\u00e8re les commandes des deux voiles tout en capotant leur cheminement jusqu\u2019au m\u00e2t, au chariot d\u2019\u00e9coute GV ou au point de tire du g\u00e9nois. Les bloqueurs plac\u00e9s en amont de ces winchs arri\u00e8res permettent de man\u0153uvrer ces deux voiles tout en \u00e9tant install\u00e9 \u00e0 la barre. En effet, l\u2019\u00e9coute de grand-voile est mont\u00e9e en s\u00e9rie \u00e0 l\u2019allemande, avec un brin revenant de chaque c\u00f4t\u00e9 du cockpit, permettant de la commander, aussi bien du winch arri\u00e8re b\u00e2bord que de celui de tribord, tout comme le G\u00e9nois. On dispose de plusieurs position pour barrer, y compris debout gr\u00e2ce aux cales bien plac\u00e9es. Des passavant larges m\u00e8nent \u00e0 l\u2019avant prot\u00e9g\u00e9s par des chandeliers et fili\u00e8res \u00e0 c\u00e2ble qui ne retiendront pas un poids lourd en passe de passer par-dessus bord\u2026 Un grand davier et un winch \u00e9lectrique compl\u00e8tent le tableau.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-20928 aligncenter size-full\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-cockpit.jpg\" alt=\"\" width=\"810\" height=\"424\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-cockpit.jpg 810w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-cockpit-480x251.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 810px, 100vw\" \/><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bb4. Un int\u00e9rieur clair et de la hauteur sous barrots\u00a0\u00bb module_id=\u00a0\u00bbtitre4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>4. Un int\u00e9rieur clair et de la hauteur sous barrots<\/h2>\n<p>L\u2019int\u00e9rieur est trait\u00e9 en bois clair, avec des plans de travail en Corian dans la cuisine. L\u2019ambiance est lumineuse gr\u00e2ce aux hublots de pont et la visibilit\u00e9 vers l\u2019ext\u00e9rieur est bonne. On se croirait -presque- dans un <strong>Deck Saloon<\/strong> ! La version que nous essayons comporte 3 cabines et deux salles d\u2019eau, de taille normales. Dans les salles d\u2019eau, on trouve un rideau de douche pliant qui ne me semble pas d\u2019une extr\u00eame solidit\u00e9. Les couchages sont des matelas mousses, sans sommier, on ne peut pas faire de miracle ! Tout l\u2019\u00e9clairage est en Led, un bon point pour le bilan \u00e9lectrique. La hauteur sous barrot varie entre 1,85 m (cabines arri\u00e8res) et 1,95 m (carr\u00e9, cabine avant) et je peux cuisiner debout \u00e0 l\u2019aise avec mon 1m92 !<\/p>\n<p><img decoding=\"async\" class=\"wp-image-20933 aligncenter size-full\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-interieur.jpg\" alt=\"\" width=\"810\" height=\"424\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-interieur.jpg 810w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-band-of-boats-interieur-480x251.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 810px, 100vw\" \/><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.bandofboats.com\/fr\/toutes-les-marques\/jeanneau\/sun-odyssey\/sun-odyssey-409?utm_source=blog&#038;utm_medium=CTA&#038;utm_campaign_article-sun-odyssey-409&Prime; url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbVoir les annonces de Sun Odyssey 409&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb admin_label=\u00a0\u00bbCTA annonces\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#063462&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_text admin_label=\u00a0\u00bb5. Syst\u00e8mes\u00a0\u00bb module_id=\u00a0\u00bbtitre5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>5. Syst\u00e8mes<\/h2>\n<h3>Gr\u00e9ement<\/h3>\n<p>Gr\u00e9e en sloop en t\u00eate, notre bateau disposer d\u2019une grand-voile semi latt\u00e9e et d\u2019un g\u00e9nois sur enrouleur \u00e0 140%. En option, on peut disposer d\u2019une grand-voile sur enrouleur, d\u2019un foc auto vireur, d\u2019un foc \u00e0 plus faible recouvrement que le n\u00f4tre ainsi que d\u2019un code z\u00e9ro.<\/p>\n<h3>\u00c9lectricit\u00e9<\/h3>\n<p>Le bateau essay\u00e9 dispose de deux packs batteries (2 x 110 Ah servitude et 1 x 110 Ah moteur et propulseur. la recharge se fait via un chargeur de quai et un alternateur 80 Ah.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-10778 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so_409_PV1.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so_409_PV1.jpg 640w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so_409_PV1-300x200.jpg 300w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so_409_PV1-585x390.jpg 585w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so_409_PV1-263x175.jpg 263w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Deux panneaux photovolta\u00efques peuvent \u00eatre mont\u00e9s sur le pont avant. Ils ne sont pas un luxe pour les r\u00e9gions ensoleill\u00e9es car sinon le bateau, si on n\u2019aime pas naviguer au diesel (Yanmar 40 chevaux), devra passer une nuit \u00e0 quai tous les 2 ou 3 nuits\u2026 Pourquoi ne pas pr\u00e9voir une installation offrant davantage d\u2019autonomie ?<\/p>\n<h3>Sanitaires<\/h3>\n<p>Avec une capacit\u00e9 de 530 L et un chauffe-eau fonctionnant sur le 220 V et via le refroidissement moteur permettent de vivre confortablement \u00e0 bord. Une cuve \u00e0 eaux noires compl\u00e8te le tableau.<\/p>\n<h3>Electronique<\/h3>\n<p>Notre bateau est \u00e9quip\u00e9 d\u2019une \u00e9lectronique Simrad, comprenant traceur orientable, speedo, an\u00e9mom\u00e8tre, pilote (offrant un mode vent). On dispose des instruments et du pilote \u00e0 chaque poste de barre, c\u2019est pratique. Le syst\u00e8me est compl\u00e9t\u00e9 par un dock et un syst\u00e8me de sonorisation permettant de relier n\u2019importe quel baladeur num\u00e9rique ou smartphone \u00e0 la sono. A noter que le bateau peut \u00eatre \u00e9quip\u00e9 d\u2019un propulseur d\u2019\u00e9trave et du nouveau syst\u00e8me \u201cDocking 360\u00b0\u201d facilitant les man\u0153uvres de port.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bb6. En navigation\u00a0\u00bb module_id=\u00a0\u00bbtitre6&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>6. En navigation<\/h2>\n<h3>A la voile par petit temps<\/h3>\n<p>Par ce beau temps (12\/15 noeuds de vent, petit clapot) le 409 est parfaitement \u00e0 son aise. La car\u00e8ne puissante taille sa route dans le clapot. Lorsqu\u2019on navigue dans les canaux entre les \u00eeles, on rencontre fr\u00e9quemment 1,5 m de clapot que les 9 tonnes du b\u00e9b\u00e9 charg\u00e9 \u00e9talent facilement. J\u2019ai toutes les commandes sous la main. A l\u2019empannage ou au virement, je laisse d\u2019abord la GV au bloqueur, vire ou empanne, reprends au winch au vent le mou d\u2019\u00e9coute de g\u00e9nois, le lib\u00e8re puis remplace cette \u00e9coute par celle de GV pour la border \u00e0 demande. Pour encore plus de facilit\u00e9, un foc auto-vireur est disponible en option. Tout ceci est tr\u00e8s pratique une fois qu\u2019on a pris le pli. On vire seul, comme sur un petit bateau, c\u2019est plaisant. Le syst\u00e8me de double barre est doux et offre un retour correct.<\/p>\n<h3>A la voile par temps frais<\/h3>\n<p>En quittant la Dominique en direction du Nord, il y a du vent ce matin, plus de 15\/18 n\u0153uds \u00e9tablis. Je sors avec un ris, avec dans l\u2019id\u00e9e de tester la r\u00e9duction au 2e en route. On passe la pointe nord de l\u2019\u00eele pour ramasser une claque ! Ma femme \u00e0 la barre, je r\u00e9duis au deuxi\u00e8me ris (prise de ris automatique), facile, sans probl\u00e8me. Mais que se passerait-il si un n\u0153ud se formait dans la bosse sous le capotage rendant le roof si \u201cflush\u201d ? La r\u00e9duction du g\u00e9nois ne pose aucun probl\u00e8me, je peux, depuis la barre man\u0153uvrer la bosse d\u2019enrouleur et l\u2019\u00e9coute de g\u00e9nois. Un peu plus tard le vent monte encore \u00e0 20\/22 n\u0153uds \u00e9tablis. Ma femme, enceinte, est un peu malade aujourd\u2019hui, et j\u2019appr\u00e9cierais de pouvoir faire route directe au pr\u00e8s pour limiter la dur\u00e9e de ce passage vers les Saintes. H\u00e9las, impossible sans 3e ris. Le b\u00e9b\u00e9 de 9 tonnes est \u00e0 ses limites, la barre est dure et d\u00e9croche et on g\u00eete beaucoup trop si j\u2019insiste. faute de mieux, je d\u00e9marre le moteur et fait piper le bateau pour finir mon trajet du jour.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bb7. Principales dimensions\u00a0\u00bb module_id=\u00a0\u00bbtitre7&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>7. Principales dimensions<\/h2>\n<ul>\n<li>Longueur hors-tout: 12.34 m<\/li>\n<li>Longueur de coque: 11.98 m<\/li>\n<li>Longueur \u00e0 la flottaison: 11 m<\/li>\n<li>Bau (largeur): 3.99 m<\/li>\n<li>Tirant d\u2019eau: 2.1 m<\/li>\n<li>Tirant d\u2019air: 18.42 m<\/li>\n<li>D\u00e9placement l\u00e8ge (Masse \u00e0vide): 7860 kg<\/li>\n<li>Masse lest: 2260 kg<\/li>\n<li>Type de lest: Font<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bb8. Conclusion\u00a0\u00bb module_id=\u00a0\u00bbtitre8&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>8. Conclusion<\/h2>\n<p>Tr\u00e8s joliment dessin\u00e9, intelligemment am\u00e9nag\u00e9 tant \u00e0 l\u2019ext\u00e9rieur et \u00e0 l\u2019int\u00e9rieur, d\u2019un niveau de finition plut\u00f4t au-dessus de la moyenne, ce Sun Odyssey 409 est attachant. Bien des efforts ont \u00e9t\u00e9 entrepris par Jeanneau pour rendre ce bateau facile \u00e0 piloter en couple. C\u2019est absolument louable et parfait pour le petit temps. En revanche, pourquoi ne pas proposer en option un 3e ris pour ceux qui souhaitent \u00e9viter l\u2019enrouleur et conserver une grand-voile latt\u00e9e tout en ayant la possibilit\u00e9 de r\u00e9duire ?<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/WJg-kd3xhi8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>D\u00e9couvrez tous nos <a href=\"https:\/\/www.bandofboats.com\/fr\/toutes-les-marques\/jeanneau\/sun-odyssey\/sun-odyssey-409\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey 409 occasion<\/a> parmi toutes nos <a href=\"https:\/\/www.bandofboats.com\/fr\/types-de-bateaux\/voilier\">annonces de voiliers<\/a>, et devenez propri\u00e9taire d&rsquo;un <a href=\"https:\/\/www.bandofboats.com\/fr\/bateaux-a-vendre\/voiliers-occasion-jeanneau\">voilier Jeanneau d&rsquo;occasion<\/a>.<\/p>\n<p>Compl\u00e9tez votre lecture et d\u00e9couvrez le Sun Odyssey 410 dans notre article <a href=\"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sun-odyssey-410\">Essai bateau sur le Sun Odyssey 410<\/a><\/p>\n<p><em>L\u2019essai est r\u00e9dig\u00e9 par Fran\u00e7ois Meyer.<\/em><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbArticles similaires\u00a0\u00bb module_id=\u00a0\u00bbtitre9&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Ces articles pourraient vous plaire<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rempla\u00e7ant le Sun Odyssey 39i, le Sun Odyssey 409 de la gamme Sun Odyssey, lanc\u00e9 en 2011, est un croiseur sportif, pens\u00e9 pour \u00eatre men\u00e9 en \u00e9quipage r\u00e9duit. Construit \u00e0 plus de 300 exemplaires et sacr\u00e9 European Yacht of The Year 2011, sa taille et ses commandes ramen\u00e9es vers le barreur m\u2019ont fait choisir ce [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<center><em>Rempla\u00e7ant le <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/marque\/jeanneau\/modele\/sun-odyssey-39-i\" target=\"_blank\" rel=\"noopener noreferrer\"> Sun Odyssey 39i<\/a>, le <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/marque\/jeanneau\/modele\/sun-odyssey-409\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey 409<\/a> de la gamme <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/marque\/jeanneau\/gamme\/sun-odyssey\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey<\/a>, lanc\u00e9 en 2011, est un croiseur sportif, pens\u00e9 pour \u00eatre men\u00e9 en \u00e9quipage r\u00e9duit. Construit \u00e0 plus de 300 exemplaires et sacr\u00e9 European Yacht of The Year 2011, sa taille et ses commandes ramen\u00e9es vers le barreur m\u2019ont fait choisir ce monocoque pour une nouvelle croisi\u00e8re de 21 jours dans les petites Antilles, l\u2019\u00e9t\u00e9, p\u00e9riode m\u00e9t\u00e9orologiquement mouvement\u00e9e peupl\u00e9e de d\u00e9pressions tropicales\u2026 <\/em><\/center><p><img class=\"aligncenter size-large wp-image-10773\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so_409_sailing1-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\" \/><\/p><h2>Des lignes tendues<\/h2><p><img class=\"aligncenter size-full wp-image-10774\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-3-4ar-hd1.jpg\" alt=\"\" width=\"640\" height=\"360\" \/><\/p><p>Bouchains saillants, hublots de pont flush, design \u00e9pur\u00e9, Philippe Briand a dessin\u00e9 une car\u00e8ne moderne et fluide pour Jeanneau. 11,98 m de long pour 3,99 m de large, le bateau d\u00e9gage une impression de puissance quand on le regarde du quai. Les deux barres \u00e0 roues d\u00e9gagent un vaste espace dans le cockpit, d\u2019autant que le radeau dispara\u00eet dans un coffre d\u00e9di\u00e9 (ou on rangera aussi la porte d\u2019acc\u00e8s au carr\u00e9). Le tableau arri\u00e8re s\u2019ouvre sur \u2153 environ, conservant deux bonnes assises de part et d\u2019autre. Une douche de pont d\u00e9livrant de l\u2019eau chaude et froide est install\u00e9e \u00e0 tribord.<\/p><h2>Une construction solide<\/h2><p><img class=\"aligncenter size-large wp-image-10775\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so409-1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><\/p><p>La coque, renforc\u00e9e par un treillis fibre de verre int\u00e9rieur, r\u00e9alis\u00e9e \u00e0 la main, est finie avec un appr\u00eat \u00e9poxy puis un Gelcoat. Le pont est moul\u00e9 par injection avec une \u00e2me en balsa discontinue. Les parties du pont soumises \u00e0 de forts efforts en sont d\u00e9pourvues. La quille est en en fonte d\u2019acier. Le bateau existe en deux versions GTE (tirant d\u2019eau de 2,10 m) et PTE (tirant d\u2019eau de 1,55m). M\u00e2t et b\u00f4me sont en aluminium, une version avec m\u00e2t \u00e0 enrouleur est disponible en option.<\/p><h2>Un plan de pont innovant<\/h2>[caption id=\"attachment_10776\" align=\"aligncenter\" width=\"800\"]<img class=\"size-full wp-image-10776\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/cockpit1.jpg\" alt=\"\" width=\"800\" height=\"600\" \/> OLYMPUS DIGITAL CAMERA[\/caption]<p><strong>Pens\u00e9 pour \u00eatre men\u00e9 par un couple<\/strong>, le <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/marque\/jeanneau\/modele\/sun-odyssey-409\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey 409<\/a> re\u00e7oit deux winchs au poste de barre (qui peuvent \u00eatre \u00e9lectrifi\u00e9s en option) et deux winchs, plus petits, sur le roof. Pour faciliter les man\u0153uvres, <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/marque\/jeanneau\" target=\"_blank\" rel=\"noopener noreferrer\">Jeanneau<\/a> a ramen\u00e9 en arri\u00e8re les commandes des deux voiles tout en capotant leur cheminement jusqu\u2019au m\u00e2t, au chariot d\u2019\u00e9coute GV ou au point de tire du g\u00e9nois. Les bloqueurs plac\u00e9s en amont de ces winchs arri\u00e8res permettent de man\u0153uvrer ces deux voiles tout en \u00e9tant install\u00e9 \u00e0 la barre. En effet, l\u2019\u00e9coute de grand-voile est mont\u00e9e en s\u00e9rie \u00e0 l\u2019allemande, avec un brin revenant de chaque c\u00f4t\u00e9 du cockpit, permettant de la commander, aussi bien du winch arri\u00e8re b\u00e2bord que de celui de tribord, tout comme le G\u00e9nois. On dispose de plusieurs position pour barrer, y compris debout gr\u00e2ce aux cales bien plac\u00e9es. Des passavant larges m\u00e8nent \u00e0 l\u2019avant prot\u00e9g\u00e9s par des chandeliers et fili\u00e8res \u00e0 c\u00e2ble qui ne retiendront pas un poids lourd en passe de passer par-dessus bord... Un grand davier et un winch \u00e9lectrique compl\u00e8tent le tableau.<\/p><h2>Un int\u00e9rieur clair et de la hauteur sous barrots<\/h2><p><img class=\"aligncenter size-large wp-image-10777\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/SO409INTERIEUR-1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><\/p><p>L\u2019int\u00e9rieur est trait\u00e9 en bois clair, avec des plans de travail en Corian dans la cuisine. L\u2019ambiance est lumineuse gr\u00e2ce aux hublots de pont et la visibilit\u00e9 vers l\u2019ext\u00e9rieur est bonne. On se croirait -presque- dans un <strong>Deck Saloon<\/strong> ! La version que nous essayons comporte 3 cabines et deux salles d\u2019eau, de taille normales. Dans les salles d\u2019eau, on trouve un rideau de douche pliant qui ne me semble pas d\u2019une extr\u00eame solidit\u00e9. Les couchages sont des matelas mousses, sans sommier, on ne peut pas faire de miracle ! Tout l\u2019\u00e9clairage est en Led, un bon point pour le bilan \u00e9lectrique. La hauteur sous barrot varie entre 1,85 m (cabines arri\u00e8res) et 1,95 m (carr\u00e9, cabine avant) et je peux cuisiner debout \u00e0 l\u2019aise avec mon 1m92 !<\/p><h2>Syst\u00e8mes<\/h2><h3>Gr\u00e9ement<\/h3><p>Gr\u00e9e en sloop en t\u00eate, notre bateau disposer d\u2019une grand-voile semi latt\u00e9e et d\u2019un g\u00e9nois sur enrouleur \u00e0 140%. En option, on peut disposer d\u2019une grand-voile sur enrouleur, d\u2019un foc auto vireur, d\u2019un foc \u00e0 plus faible recouvrement que le n\u00f4tre ainsi que d'un code z\u00e9ro.<\/p><h3>Electricit\u00e9<\/h3><p><img class=\"aligncenter size-full wp-image-10778\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/so_409_PV1.jpg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p><p>Le bateau essay\u00e9 dispose de deux packs batteries (2 x 110 Ah servitude et 1 x 110 Ah moteur et propulseur. la recharge se fait via un chargeur de quai et un alternateur 80 Ah.<br \/>Deux panneaux photovolta\u00efques peuvent \u00eatre mont\u00e9s sur le pont avant. Ils ne sont pas un luxe pour les r\u00e9gions ensoleill\u00e9es car sinon le bateau, si on n\u2019aime pas naviguer au diesel (Yanmar 40 chevaux), devra passer une nuit \u00e0 quai tous les 2 ou 3 nuits\u2026 Pourquoi ne pas pr\u00e9voir une installation offrant davantage d\u2019autonomie ?<\/p><h3>Sanitaires<\/h3><p>Avec une capacit\u00e9 de 530 L et un chauffe-eau fonctionnant sur le 220 V et via le refroidissement moteur permettent de vivre confortablement \u00e0 bord. Une cuve \u00e0 eaux noires compl\u00e8te le tableau.<\/p><h3>Electronique<\/h3><p>Notre bateau est \u00e9quip\u00e9 d\u2019une \u00e9lectronique Simrad, comprenant traceur orientable, speedo, an\u00e9mom\u00e8tre, pilote (offrant un mode vent). On dispose des instruments et du pilote \u00e0 chaque poste de barre, c\u2019est pratique. Le syst\u00e8me est compl\u00e9t\u00e9 par un dock et un syst\u00e8me de sonorisation permettant de relier n\u2019importe quel baladeur num\u00e9rique ou smartphone \u00e0 la sono. A noter que le bateau peut \u00eatre \u00e9quip\u00e9 d\u2019un propulseur d\u2019\u00e9trave et du nouveau syst\u00e8me \u201cDocking 360\u00b0\u201d facilitant les man\u0153uvres de port.<\/p><h2>En navigation<\/h2><h3>A la voile par petit temps<\/h3><p>Par ce beau temps (12\/15 noeuds de vent, petit clapot) le 409 est parfaitement \u00e0 son aise. La car\u00e8ne puissante taille sa route dans le clapot. Lorsqu\u2019on navigue dans les canaux entre les \u00eeles, on rencontre fr\u00e9quemment 1,5 m de clapot que les 9 tonnes du b\u00e9b\u00e9 charg\u00e9 \u00e9talent facilement. J\u2019ai toutes les commandes sous la main. A l\u2019empannage ou au virement, je laisse d\u2019abord la GV au bloqueur, vire ou empanne, reprends au winch au vent le mou d\u2019\u00e9coute de g\u00e9nois, le lib\u00e8re puis remplace cette \u00e9coute par celle de GV pour la border \u00e0 demande. Pour encore plus de facilit\u00e9, un foc auto-vireur est disponible en option. Tout ceci est tr\u00e8s pratique une fois qu\u2019on a pris le pli. On vire seul, comme sur un petit bateau, c\u2019est plaisant. Le syst\u00e8me de double barre est doux et offre un retour correct.<\/p><h3>A la voile par temps frais<\/h3><p>En quittant la Dominique en direction du Nord, il y a du vent ce matin, plus de 15\/18 n\u0153uds \u00e9tablis. Je sors avec un ris, avec dans l\u2019id\u00e9e de tester la r\u00e9duction au 2e en route. On passe la pointe nord de l\u2019\u00eele pour ramasser une claque ! Ma femme \u00e0 la barre, je r\u00e9duis au deuxi\u00e8me ris (prise de ris automatique), facile, sans probl\u00e8me. Mais que se passerait-il si un n\u0153ud se formait dans la bosse sous le capotage rendant le roof si \u201cflush\u201d ? La r\u00e9duction du g\u00e9nois ne pose aucun probl\u00e8me, je peux, depuis la barre man\u0153uvrer la bosse d\u2019enrouleur et l\u2019\u00e9coute de g\u00e9nois. Un peu plus tard le vent monte encore \u00e0 20\/22 n\u0153uds \u00e9tablis. Ma femme, enceinte, est un peu malade aujourd\u2019hui, et j\u2019appr\u00e9cierais de pouvoir faire route directe au pr\u00e8s pour limiter la dur\u00e9e de ce passage vers les Saintes. H\u00e9las, impossible sans 3e ris. Le b\u00e9b\u00e9 de 9 tonnes est \u00e0 ses limites, la barre est dure et d\u00e9croche et on g\u00eete beaucoup trop si j\u2019insiste. faute de mieux, je d\u00e9marre le moteur et fait piper le bateau pour finir mon trajet du jour.<\/p><h2>Conclusion<\/h2><p><strong>Tr\u00e8s joliment dessin\u00e9, intelligemment am\u00e9nag\u00e9 tant \u00e0 l\u2019ext\u00e9rieur et \u00e0 l\u2019int\u00e9rieur, d\u2019un niveau de finition plut\u00f4t au-dessus de la moyenne, ce <a href=\"https:\/\/www.bandofboats.com\/en\/buy\/brand\/jeanneau\/model\/sun-odyssey-409\" target=\"_blank\" rel=\"noopener noreferrer\">Sun Odyssey 409 <\/a>est attachant. Bien des efforts ont \u00e9t\u00e9 entrepris par <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/marque\/jeanneau\" target=\"_blank\" rel=\"noopener noreferrer\">Jeanneau<\/a> pour rendre ce bateau facile \u00e0 piloter en couple. C\u2019est absolument louable et parfait pour le petit temps. En revanche, pourquoi ne pas proposer en option un 3e ris pour ceux qui souhaitent \u00e9viter l\u2019enrouleur et conserver une grand-voile latt\u00e9e tout en ayant la possibilit\u00e9 de r\u00e9duire ?<\/strong><\/p><p><img class=\"aligncenter size-full wp-image-10779\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-plan-j-3c1t1.jpg\" alt=\"\" width=\"640\" height=\"226\" \/><\/p><p><img class=\"aligncenter size-full wp-image-10780\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-plan-j-2c1t1.jpg\" alt=\"\" width=\"640\" height=\"224\" \/><\/p><p><img class=\"aligncenter size-full wp-image-10781\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/sun-odyssey-409-plan-j-de-pont1.jpg\" alt=\"\" width=\"640\" height=\"218\" \/><\/p><p>D\u00e9couvrez tous nos <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/marque\/jeanneau\/modele\/sun-odyssey-409\" target=\"_blank\" rel=\"noopener noreferrer\"> Sun Odyssey 409 occasion <\/a> parmi nos <a href=\"https:\/\/www.bandofboats.com\/fr\/buy\/\" target=\"_blank\" rel=\"noopener noreferrer\">annonces bateaux <\/a>, et devenez propri\u00e9taire de ce mod\u00e8le Jeanneau.<\/p><p><em>L'essai est r\u00e9dig\u00e9 par <a href=\"http:\/\/www.intotheboat.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fran\u00e7ois Meyer<\/a>.<\/em><\/p><h2>Principales dimensions<\/h2><p>Longueur hors-tout: 12.34 m<br \/>Longueur de coque: 11.98 m<br \/>Longueur \u00e0 la flottaison: 11 m<br \/>Bau (largeur): 3.99 m<br \/>Tirant d'eau: 2.1 m<br \/>Tirant d'air: 18.42 m<br \/>D\u00e9placement l\u00e8ge (Masse \u00e0vide): 7860 kg<br \/>Masse lest: 2260 kg<br \/>Type de lest: Fonte<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[650],"tags":[],"class_list":["post-10754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-essais-voiliers-et-catamarans"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Essai Bateau sur le Sun Odyssey 409 - Band of Boats<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez \u00e0 travers cet essai bateau, la navigation \u00e0 bord du Sun Odyssey 409, mod\u00e8le incontournable de chez Jeanneau.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Essai Bateau sur le Sun Odyssey 409 - Band of Boats\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez \u00e0 travers cet essai bateau, la navigation \u00e0 bord du Sun Odyssey 409, mod\u00e8le incontournable de chez Jeanneau.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/\" \/>\n<meta property=\"og:site_name\" content=\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-24T08:44:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T16:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/SO409-Pres-e1570476675705.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"headline\":\"Essai Bateau sur le Sun Odyssey 409\",\"datePublished\":\"2019-10-24T08:44:21+00:00\",\"dateModified\":\"2024-01-22T16:59:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/\"},\"wordCount\":2108,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/SO409-Pres-e1570476675705.jpg\",\"articleSection\":[\"Essais voiliers et catamarans\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/\",\"name\":\"Essai Bateau sur le Sun Odyssey 409 - Band of Boats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/SO409-Pres-e1570476675705.jpg\",\"datePublished\":\"2019-10-24T08:44:21+00:00\",\"dateModified\":\"2024-01-22T16:59:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"description\":\"D\u00e9couvrez \u00e0 travers cet essai bateau, la navigation \u00e0 bord du Sun Odyssey 409, mod\u00e8le incontournable de chez Jeanneau.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/SO409-Pres-e1570476675705.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/SO409-Pres-e1570476675705.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/essai-bateau-sur-le-sun-odyssey-409\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Essai Bateau sur le Sun Odyssey 409\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/\",\"name\":\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/fr\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Essai Bateau sur le Sun Odyssey 409 - Band of Boats","description":"D\u00e9couvrez \u00e0 travers cet essai bateau, la navigation \u00e0 bord du Sun Odyssey 409, mod\u00e8le incontournable de chez Jeanneau.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/","og_locale":"fr_FR","og_type":"article","og_title":"Essai Bateau sur le Sun Odyssey 409 - Band of Boats","og_description":"D\u00e9couvrez \u00e0 travers cet essai bateau, la navigation \u00e0 bord du Sun Odyssey 409, mod\u00e8le incontournable de chez Jeanneau.","og_url":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/","og_site_name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","article_published_time":"2019-10-24T08:44:21+00:00","article_modified_time":"2024-01-22T16:59:51+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/SO409-Pres-e1570476675705.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#article","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/"},"author":{"name":"admin","@id":"https:\/\/blog.bandofboats.com\/fr\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"headline":"Essai Bateau sur le Sun Odyssey 409","datePublished":"2019-10-24T08:44:21+00:00","dateModified":"2024-01-22T16:59:51+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/"},"wordCount":2108,"commentCount":0,"image":{"@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/SO409-Pres-e1570476675705.jpg","articleSection":["Essais voiliers et catamarans"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/","url":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/","name":"Essai Bateau sur le Sun Odyssey 409 - Band of Boats","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#primaryimage"},"image":{"@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/SO409-Pres-e1570476675705.jpg","datePublished":"2019-10-24T08:44:21+00:00","dateModified":"2024-01-22T16:59:51+00:00","author":{"@id":"https:\/\/blog.bandofboats.com\/fr\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"description":"D\u00e9couvrez \u00e0 travers cet essai bateau, la navigation \u00e0 bord du Sun Odyssey 409, mod\u00e8le incontournable de chez Jeanneau.","breadcrumb":{"@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#primaryimage","url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/SO409-Pres-e1570476675705.jpg","contentUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/10\/SO409-Pres-e1570476675705.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/blog.bandofboats.com\/fr\/essai-bateau-sur-le-sun-odyssey-409\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.bandofboats.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Essai Bateau sur le Sun Odyssey 409"}]},{"@type":"WebSite","@id":"https:\/\/blog.bandofboats.com\/fr\/#website","url":"https:\/\/blog.bandofboats.com\/fr\/","name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.bandofboats.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.bandofboats.com\/fr\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/posts\/10754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/comments?post=10754"}],"version-history":[{"count":0,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/posts\/10754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/media\/10771"}],"wp:attachment":[{"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/media?parent=10754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/categories?post=10754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/fr\/wp-json\/wp\/v2\/tags?post=10754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}