{"id":9896,"date":"2019-06-13T18:02:57","date_gmt":"2019-06-13T16:02:57","guid":{"rendered":"https:\/\/blog.bandofboats.com\/?p=9896"},"modified":"2021-11-26T18:05:09","modified_gmt":"2021-11-26T17:05:09","slug":"las-bombas-de-achique-en-los-barcos-de-recreo","status":"publish","type":"post","link":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/","title":{"rendered":"Las bombas de achique en los barcos de recreo"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb3.22&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.11.1&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbChap\u00f4 de l&#8217;article\u00bb _builder_version=\u00bb4.11.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbSource Sans Pro|600|||||||\u00bb text_text_color=\u00bb#063462&#8243; text_font_size=\u00bb18px\u00bb custom_padding=\u00bb30px||0px||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<strong>Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n.<\/strong> Tambi\u00e9n permiten evacuar peque\u00f1as cantidades de agua presentes en los fondos.<\/p>\n<p>Aunque la presencia a bordo \u201cde un dispositivo de achique manual\u201d sea obligatorio, por lo general no resulta suficiente para frenar una entrada de agua importante. Por esta raz\u00f3n, <strong>las bombas de achique modernas de las embarcaciones de recreo suelen ser el\u00e9ctricas<\/strong> y funcionan con corriente continua (12 o 24 V).<\/p>\n<p>\u00c9stas puede ser <strong>manuales<\/strong>, <strong>autom\u00e1ticas <\/strong>o <strong>accionarse a trav\u00e9s de un disparador<\/strong>. Se pueden instalar de manera fija o disponer de modelos m\u00f3viles que pueden situarse lo m\u00e1s cerca posible de la entrada de agua.<\/p>\n<p><strong>Una v\u00eda de agua en un casco de un di\u00e1metro de 150 mm dejar\u00e1 entrar m\u00e1s de 30 m3 de agua por hora (30 000 litros) a bordo<\/strong>. Se trata de un volumen enorme que solo podr\u00e1 frenarse utilizando un sistema de bombeo adaptado.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9599 size-medium aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe1-300x152.jpg\" alt=\"\" width=\"300\" height=\"152\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe1-300x152.jpg 300w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe1.jpg 408w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Para sacarle el mayor provecho posible a su(s) bomba(s) de achique, en caso de emergencia, conviene tener en cuenta varios detalles importantes:<\/p>\n<ul>\n<li>Limitar la longitud de las canalizaciones de expulsi\u00f3n y de aspiraci\u00f3n (los tubos ejercen una resistencia importante \u2013la fricci\u00f3n\u2013 por lo que cuanto desde cuanto m\u00e1s lejos haya que bombear, menos elevado ser\u00e1 su caudal). <strong>Idealmente, la distancia entre la bomba y el pasacascos no debe superior a 1 m.<\/strong><\/li>\n<li>Limite los esfuerzos de la bomba dimensionando correctamente el tubo de expulsi\u00f3n (26 mm para una bomba media y 36 mm para una bomba de gran capacidad).<\/li>\n<li>Instale siempre una sola bomba por l\u00ednea de expulsi\u00f3n. Dos bombas montadas en una l\u00ednea no funcionan mejor que una sola.<\/li>\n<li>Limpie regularmente los fondos eliminando cualquier resto que pueda bloquear un contactor o da\u00f1ar una bomba.<\/li>\n<li>Pruebe regularmente el funcionamiento de su(s) bomba(s) de achique.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"wp-image-9600 size-medium aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe2-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe2-300x199.jpg 300w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe2-263x175.jpg 263w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe2.jpg 307w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>[\/et_pb_text][et_pb_text admin_label=\u00bbSommaire\u00bb _builder_version=\u00bb4.11.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbSource Sans Pro|600|||||||\u00bb text_line_height=\u00bb2em\u00bb link_text_color=\u00bb#3e6a91&#8243; background_color=\u00bb#fef9f5&#8243; module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb50px||0px||false|false\u00bb custom_padding=\u00bb30px|30px|30px|80px|false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Resumen<\/h2>\n<p>1 &#8211; <a href=\"#titre1\">Las bombas de achique manuales<\/a><br \/>2 &#8211; <a href=\"#titre2\">Las bombas de achique el\u00e9ctricas<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbParagraphe 1&#8243; module_id=\u00bbtitre1&#8243; _builder_version=\u00bb4.11.1&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb50px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>1. Las bombas de achique manuales<\/h2>\n<p>Las bombas fijas de achique manual requieren la fuerza muscular permanente de un miembro de la tripulaci\u00f3n para hacerlas funcionar. Este miembro no puede participar en el colmatado de la entrada de agua. 6 000 L\/h.<\/p>\n<p>Bomba manual Whale titan<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9601 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe3.jpg\" alt=\"\" width=\"116\" height=\"210\" \/><\/p>\n<p>Una bomba m\u00f3vil con un caudal de 2 000 L\/h, podr\u00e1 evacuar una entrada de agua de un di\u00e1metro de 3 cm.<\/p>\n<p>Bomba manual Plastimo<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9602 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe4.jpg\" alt=\"\" width=\"117\" height=\"157\" \/><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbParagraphe 1&#8243; module_id=\u00bbtitre2&#8243; _builder_version=\u00bb4.11.1&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb50px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>2. Las bombas de achique el\u00e9ctricas<\/h2>\n<p>Las bombas sumergidas poseen unas longitudes de tubo m\u00e1s cortas y, por tanto, unas mayores capacidades de expulsi\u00f3n.<\/p>\n<p>Las bombas port\u00e1tiles, aunque poseen unas capacidades de expulsi\u00f3n menores (resistencia de los tubos de aspiraci\u00f3n), su alcachofa (extremo del tubo de aspiraci\u00f3n) puede situarse hasta en el rinc\u00f3n m\u00e1s escondido de una bodega exigua.<\/p>\n<p><strong>Las bombas de achique sumergidas fijas con un contactor externo<\/strong> suelen ser las bombas m\u00e1s potentes.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9603 size-medium aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe5-300x270.jpg\" alt=\"\" width=\"300\" height=\"270\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe5-300x270.jpg 300w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe5.jpg 313w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>\u00c9stas se activan mediante un interruptor o a trav\u00e9s de un contactor y bombean hasta 14 000 L\/h. La instalaci\u00f3n de dos de estas bombas, cada una dotada de su propio pasacascos de expulsi\u00f3n, aumenta enormemente las posibilidades de que un crucero de altura pueda frenar una v\u00eda de agua importante si el sistema el\u00e9ctrico de a bordo funciona.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9604 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe6.jpg\" alt=\"\" width=\"271\" height=\"270\" srcset=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe6.jpg 271w, https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe6-150x150.jpg 150w\" sizes=\"(max-width: 271px) 100vw, 271px\" \/><\/p>\n<p>Una bomba alternativa de instalaci\u00f3n fija compuesta por una segunda bomba de achique (y por su segundo pasacascos) consiste en disponer a bordo de una potente bomba de achique el\u00e9ctrica m\u00f3vil sumergida con una capacidad que puede alcanzar hasta 10 000 L\/h.<\/p>\n<p>Gianneschi Maxi Sub<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9605 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe7.jpg\" alt=\"\" width=\"186\" height=\"254\" \/><\/p>\n<p>Las bombas de achique sumergidas autom\u00e1ticas funcionan sin contactor, pero conforme a un ciclo que se repite infinitamente: un accionamiento de una segunda bomba cada dos minutos; en caso de que haya agua, la bomba sigue trabajando hasta el pr\u00f3ximo inicio. Aunque estos sistemas electr\u00f3nicos permiten prescindir de un contactor, los motores de las bombas est\u00e1n sometidos a un mayor esfuerzo que con los modelos con contactores. 7 500 L\/h.<\/p>\n<p>Rule RL053<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9606 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe8.jpg\" alt=\"\" width=\"129\" height=\"249\" \/><\/p>\n<p>Estos modelos tambi\u00e9n se encuentran disponibles en versi\u00f3n compacta (menos de 21 mm de altura) para las peque\u00f1as embarcaciones con fondos de bodega poco profundos. Pero tenga en cuenta que la capacidad de expulsi\u00f3n es m\u00e1s reducida, de 3 400 L\/h.<\/p>\n<p>Rule Lopro<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9607 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe9.jpg\" alt=\"\" width=\"177\" height=\"103\" \/><\/p>\n<p>En las bombas de achique sumergidas con disparador incorporado, el cajet\u00edn contiene un flotador que activa la bomba cuando el agua supera una determinada altura. Se trata de sistemas compactos de potencia media (4 000 L\/h).<\/p>\n<p>Podr\u00e1 encontrar el Rule RM 1100.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9608 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe10.jpg\" alt=\"\" width=\"254\" height=\"251\" \/><\/p>\n<p>Las bombas de achique port\u00e1tiles con cuerpo de bronce y rotor flexible pueden evacuar aguas cargadas de hidrocarburos o aguas de balaste a trav\u00e9s de su alcachofa que puede alojarse en cualquier lugar, incluso en uno inaccesible.<\/p>\n<p>Puede encontrar la Marco UP1 que bombea 5 000 L\/h<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9609 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe11.jpg\" alt=\"\" width=\"209\" height=\"149\" \/><\/p>\n<p>Las bombas de achique port\u00e1tiles con diafragma funcionan en seco sin estropearse, pero solo aspiran agua limpia.<\/p>\n<p>Puede encontrar la Jabsco 33600 que bombea 2 000 L\/h<\/p>\n<p><img decoding=\"async\" class=\"wp-image-9610 size-full aligncenter\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe12.jpg\" alt=\"\" width=\"251\" height=\"208\" \/><\/p>\n<p><strong>Para poder contar con su bomba de achique en el momento adecuado, mantenga limpios los fondos de bodega.<\/strong><\/p>\n<p><strong>Ser\u00eda una l\u00e1stima que un por un simple despojo, la bomba se bloquease en el momento crucial y enviase su embarcaci\u00f3n a pique\u2026<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n. Tambi\u00e9n permiten evacuar peque\u00f1as cantidades de agua presentes en los fondos. Aunque la presencia a bordo \u201cde un dispositivo de achique manual\u201d sea obligatorio, por lo general no resulta suficiente para frenar una entrada de agua importante. Por esta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<center><em>Les pompes de cales modernes permettent de maintenir th\u00e9oriquement le bateau \u00e0 flot en cas de voie d\u2019eau. Elles permettent \u00e9galement d\u2019\u00e9vacuer les petites quantit\u00e9s d\u2019eau pr\u00e9sentes dans les fonds.<\/em><\/center><p><strong>Les pompes de cales modernes permettent de maintenir th\u00e9oriquement le bateau \u00e0 flot en cas de voie d\u2019eau. Elles permettent \u00e9galement d\u2019\u00e9vacuer les petites quantit\u00e9s d\u2019eau pr\u00e9sentes dans les fonds.<\/strong><\/p><p>Bien que la pr\u00e9sence \u00e0 bord \u201cd\u2019un dispositif d\u2019ass\u00e8chement manuel\u201d soit obligatoire (<a href=\"https:\/\/www.legifrance.gouv.fr\/affichTexte.do?cidTexte=JORFTEXT000029884412&categorieLien=id\" target=\"_blank\" rel=\"noopener noreferrer\">Art. 240-2.05 de l\u2019arr\u00eat\u00e9 du 02\/12\/2014<\/a>) , il n\u2019est en g\u00e9n\u00e9ral pas suffisant pour \u00e9taler une entr\u00e9e d\u2019eau s\u00e9rieuse.<\/p><p>Pour cette raison, <strong>les pompes de cale modernes des bateaux de plaisance<\/strong> sont en g\u00e9n\u00e9ral <strong>\u00e9lectriques <\/strong>et fonctionnent en courant continu (12 ou 24 V).<\/p><p>Elles peuvent \u00eatre <strong>manuelles <\/strong>(d\u00e9clenchement volontaire), automatiques (d\u00e9clenchement cyclique) ou actionn\u00e9es via un d\u00e9clencheur (un contacteur \u00e0 flotteur). On peut les installer \u00e0 demeure o\u00f9 disposer de mod\u00e8les mobiles \u00e0 placer au plus pr\u00e8s de l\u2019entr\u00e9e d\u2019eau.<\/p><p><strong>Une voie d\u2019eau sur une coque sur un diam\u00e8tre de 150 mm laissera entrer plus de 30 m3 d\u2019eau par heure (30 000 Litres) \u00e0 bord<\/strong>. C\u2019est un volume gigantesque qui ne pourra \u00eatre \u00e9tal\u00e9 qu\u2019en pr\u00e9sence d\u2019un syst\u00e8me de pompage adapt\u00e9.<\/p><p><strong>Pour tirer la meilleure performance possible de votre (vos) pompe(s) de cale, en cas d\u2019urgence, plusieurs d\u00e9tails sont importants :<\/strong><\/p><center><img class=\"alignnone size-medium wp-image-17111\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe1-300x152.jpg\" alt=\"\" width=\"300\" height=\"152\" \/><\/center><p>- Limiter la longueur des canalisations de refoulement et d\u2019aspiration (les tuyaux exercent une r\u00e9sistance importante -le frottement- ainsi plus la pompe doit pomper loin, moins son d\u00e9bit sera \u00e9lev\u00e9).<\/p><p><strong>Id\u00e9alement la distance entre la pompe et le passe coque ne doit pas \u00eatre sup\u00e9rieure \u00e0 1 m.<\/strong><\/p><p>- Veillez \u00e0 limiter les efforts de la pompe en dimensionnant correctement le tuyau de refoulement (26 mm pour une pompe moyenne et 36 mm pour une pompe de forte capacit\u00e9).<br \/>- Toujours installer une seule pompe par ligne de refoulement. Deux pompes mont\u00e9es sur une ligne ne fonctionnent pas mieux qu\u2019une seule.<br \/>- Nettoyez r\u00e9guli\u00e8rement les fonds de tous d\u00e9bris qui peuvent bloquer un contacteur ou endommager une pompe.<\/p><center><img class=\"alignnone size-medium wp-image-9600\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe2-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" \/><\/center><p>- Testez r\u00e9guli\u00e8rement le fonctionnement de votre (vos) pompe(s) de cale.<\/p><center><strong>Les pompes de cale manuelles<\/strong><\/center><p>Les pompes de fixe cales manuelles n\u00e9cessitent la force musculaire permanente d\u2019un \u00e9quipier pour fonctionner. L\u2019\u00e9quipier qui pompe ne peut pas participer au colmatage de l\u2019entr\u00e9e d\u2019eau. 6 000 L\/h.<\/p><p>Vous pourrez utliser la pompe manuelle Whale titan.<\/p><center><img class=\"alignnone size-full wp-image-9601\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe3.jpg\" alt=\"\" width=\"116\" height=\"210\" \/><\/center><p>Une pompe mobile, d\u00e9bit de l\u2019ordre de 2 000 L\/h, pourra \u00e9vacuer une entr\u00e9e d\u2019eau d\u2019un diam\u00e8tre de 3 cm.<br \/>Voici la Pompe \u00e0 main Plastimo.<\/p><center><img class=\"alignnone size-full wp-image-9602\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe4.jpg\" alt=\"\" width=\"117\" height=\"157\" \/><\/center><center><strong>Les pompes de cale \u00e9lectriques<\/strong><\/center><p> <\/p><p>Certaines pompes de cales \u00e9lectriques sont immerg\u00e9es et d\u2019autres d\u00e9port\u00e9es. Les pompes immerg\u00e9es pr\u00e9sentent des longueurs de tuyaux plus courtes et donc des capacit\u00e9s de refoulement plus importantes.<\/p><p>Les pompes d\u00e9port\u00e9es, bien qu\u2019elles pr\u00e9sentent des capacit\u00e9s de refoulement plus faibles (r\u00e9sistance des tuyaux d\u2019aspiration), leur cr\u00e9pine (extr\u00e9mit\u00e9 du tuyau d'aspiration) peut \u00eatre plac\u00e9e au fin fond d\u2019une cale exigu\u00eb.<\/p><p><u>Les pompes de cales immerg\u00e9es fixes \u00e0 contacteur externe<\/u> sont en g\u00e9n\u00e9ral les pompes les plus puissantes.<\/p><center><img class=\"alignnone size-medium wp-image-9603\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe5-300x270.jpg\" alt=\"\" width=\"300\" height=\"270\" \/><\/center><p>D\u00e9clenchables par un interrupteur ou via un contacteur, elles pompent jusqu\u2019\u00e0 14 000 L\/h. L\u2019installation de deux de ces pompes, disposant chacune de son propre passe-coque de refoulement augmente s\u00e9rieusement les chances d\u2019un croiseur hauturier de pouvoir \u00e9taler une voie d\u2019eau importante si le syst\u00e8me \u00e9lectrique du bord demeure fonctionnel.<\/p><center><img class=\"alignnone size-full wp-image-9604\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe6.jpg\" alt=\"\" width=\"271\" height=\"270\" \/><\/center><p>Une bonne alternative \u00e0 l\u2019installation fixe d\u2019une seconde pompe de cale (et de son second passe coque) consiste \u00e0 disposer \u00e0 bord d\u2019une pompe de cale \u00e9lectrique mobile immerg\u00e9e puissante d\u2019une capacit\u00e9 pouvant aller jusqu\u2019\u00e0 10 000 L\/h.<\/p><p>Vous pourrez utiliser le Gianneschi Maxi Sub.<\/p><center><img class=\"alignnone size-full wp-image-9605\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe7.jpg\" alt=\"\" width=\"186\" height=\"254\" \/><\/center><p>Les pompes de cales immerg\u00e9es automatiques fonctionnent sans contacteur, mais selon un cycle se r\u00e9p\u00e9tant \u00e0 l\u2019infini : un d\u00e9marrage d\u2019une seconde toute les deux minutes ; en cas de pr\u00e9sence d\u2019eau, la pompe continue \u00e0 travailler jusqu\u2019au prochain d\u00e9marrage. Si ces syst\u00e8mes \u00e9lectroniques permettent de se passer de contacteur, les moteurs des pompes sont sollicit\u00e9s bien davantage que sur des mod\u00e8les \u00e0 contacteurs. 7 500 L\/h.<\/p><p>Voici le Rule RL053.<\/p><center><img class=\"alignnone size-full wp-image-9606\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe8.jpg\" alt=\"\" width=\"129\" height=\"249\" \/><\/center><p>Ces m\u00eames mod\u00e8les existent en aussi en version compacte (moins de 21 mm de hauteur) pour les petits bateaux aux fonds de cales peu profonds. Attention la capacit\u00e9 de refoulement est plus faible, 3 400 L\/h.<\/p><p>Optez pour le Rule Lopro, un mod\u00e8le compact<\/p><center><img class=\"alignnone size-full wp-image-9607\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe9.jpg\" alt=\"\" width=\"177\" height=\"103\" \/><\/center><p>Sur les pompes de cales immerg\u00e9es \u00e0 d\u00e9clencheur int\u00e9gr\u00e9, le bo\u00eetier renferme un flotteur d\u00e9clenchant la pompe au-del\u00e0 d\u2019une certaine hauteur d\u2019eau. Ce sont des syst\u00e8mes compacts de puissance moyenne (4 000 L\/h).<\/p><p>Vous pourrez trouver le Rule RM 1100.<\/p><center><img class=\"alignnone size-full wp-image-9608\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe10.jpg\" alt=\"\" width=\"254\" height=\"251\" \/><\/center><p>Les pompe de cales d\u00e9port\u00e9es \u00e0 corps en bronze et rotor flexible peuvent \u00e9vacuer des eaux charg\u00e9es d'hydrocarbures ou eaux de ballast via leur cr\u00e9pine logeable n\u2019importe ou m\u00eame dans un endroit inaccessible.<\/p><p>Vous pourrez trouver Marco UP1 pompant 5 000 L\/h.<\/p><center><img class=\"alignnone size-full wp-image-9609\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe11.jpg\" alt=\"\" width=\"209\" height=\"149\" \/><\/center><p>Les pompe de cales d\u00e9port\u00e9es \u00e0 diaphragme, fonctionnent \u00e0 sec sans \u00eatre ab\u00eem\u00e9es, mais aspirent uniquement des eaux propres.<\/p><p>Vous pourrez trouver Jabsco 33600 pompant 2 000 L\/h.<\/p><center><img class=\"alignnone size-full wp-image-9610\" src=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe12.jpg\" alt=\"\" width=\"251\" height=\"208\" \/><\/center><p><strong>Pour pouvoir compter sur votre pompe de cale au bon moment, maintenez propres vos fonds de cale.<\/strong><\/p><p>Il serait dommage qu\u2019un simple d\u00e9bris, en bloquant la pompe au moment crucial, envoie votre bateau par le fond...<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-9896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las bombas de achique en los barcos de recreo - Band of Boats<\/title>\n<meta name=\"description\" content=\"Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n - Band of Boats te propone analizar las bombas..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las bombas de achique en los barcos de recreo - Band of Boats\" \/>\n<meta property=\"og:description\" content=\"Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n - Band of Boats te propone analizar las bombas..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/\" \/>\n<meta property=\"og:site_name\" content=\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-13T16:02:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T17:05:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe_de_cale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"headline\":\"Las bombas de achique en los barcos de recreo\",\"datePublished\":\"2019-06-13T16:02:57+00:00\",\"dateModified\":\"2021-11-26T17:05:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/\"},\"wordCount\":1096,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/pompe_de_cale.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/\",\"name\":\"Las bombas de achique en los barcos de recreo - Band of Boats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/pompe_de_cale.jpg\",\"datePublished\":\"2019-06-13T16:02:57+00:00\",\"dateModified\":\"2021-11-26T17:05:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\"},\"description\":\"Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n - Band of Boats te propone analizar las bombas..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/pompe_de_cale.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.bandofboats.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/pompe_de_cale.jpg\",\"width\":450,\"height\":300,\"caption\":\"pompe_de_cale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/las-bombas-de-achique-en-los-barcos-de-recreo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las bombas de achique en los barcos de recreo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/\",\"name\":\"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.bandofboats.com\\\/es\\\/#\\\/schema\\\/person\\\/aaa53ed189fbb462a818be04712c48cb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las bombas de achique en los barcos de recreo - Band of Boats","description":"Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n - Band of Boats te propone analizar las bombas..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/","og_locale":"es_ES","og_type":"article","og_title":"Las bombas de achique en los barcos de recreo - Band of Boats","og_description":"Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n - Band of Boats te propone analizar las bombas..","og_url":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/","og_site_name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","article_published_time":"2019-06-13T16:02:57+00:00","article_modified_time":"2021-11-26T17:05:09+00:00","og_image":[{"width":450,"height":300,"url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe_de_cale.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#article","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/"},"author":{"name":"admin","@id":"https:\/\/blog.bandofboats.com\/es\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"headline":"Las bombas de achique en los barcos de recreo","datePublished":"2019-06-13T16:02:57+00:00","dateModified":"2021-11-26T17:05:09+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/"},"wordCount":1096,"commentCount":0,"image":{"@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe_de_cale.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/","url":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/","name":"Las bombas de achique en los barcos de recreo - Band of Boats","isPartOf":{"@id":"https:\/\/blog.bandofboats.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#primaryimage"},"image":{"@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe_de_cale.jpg","datePublished":"2019-06-13T16:02:57+00:00","dateModified":"2021-11-26T17:05:09+00:00","author":{"@id":"https:\/\/blog.bandofboats.com\/es\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb"},"description":"Las bombas de achique modernas permiten mantener te\u00f3ricamente el barco a flote en caso de filtraci\u00f3n - Band of Boats te propone analizar las bombas..","breadcrumb":{"@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#primaryimage","url":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe_de_cale.jpg","contentUrl":"https:\/\/blog.bandofboats.com\/wp-content\/uploads\/2019\/06\/pompe_de_cale.jpg","width":450,"height":300,"caption":"pompe_de_cale"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.bandofboats.com\/es\/las-bombas-de-achique-en-los-barcos-de-recreo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.bandofboats.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las bombas de achique en los barcos de recreo"}]},{"@type":"WebSite","@id":"https:\/\/blog.bandofboats.com\/es\/#website","url":"https:\/\/blog.bandofboats.com\/es\/","name":"Band of Boats, achat et vente de bateaux neufs et d&#039;occasion","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.bandofboats.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.bandofboats.com\/es\/#\/schema\/person\/aaa53ed189fbb462a818be04712c48cb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc90f067119894d29463b1b397664f5e1232f9ccaa018bb0bf4d6bd70143243?s=96&d=blank&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/posts\/9896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/comments?post=9896"}],"version-history":[{"count":0,"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/posts\/9896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/media\/17112"}],"wp:attachment":[{"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/media?parent=9896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/categories?post=9896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.bandofboats.com\/es\/wp-json\/wp\/v2\/tags?post=9896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}